{"id":4005,"date":"2019-09-27T02:48:25","date_gmt":"2019-09-27T02:48:25","guid":{"rendered":"http:\/\/localhost:8888\/fitpass\/?p=4005"},"modified":"2025-07-09T19:16:07","modified_gmt":"2025-07-09T19:16:07","slug":"emotional-fitness-training-gdl","status":"publish","type":"post","link":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/","title":{"rendered":"Emotional Fitness Training GDL"},"content":{"rendered":"<div data-draftjs-conductor-fragment=\"{&quot;blocks&quot;:[{&quot;key&quot;:&quot;15a3e&quot;,&quot;text&quot;:&quot;Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;c2l4f&quot;,&quot;text&quot;:&quot; &quot;,&quot;type&quot;:&quot;atomic&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:1,&quot;key&quot;:0}],&quot;data&quot;:{}},{&quot;key&quot;:&quot;dnr3s&quot;,&quot;text&quot;:&quot;Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:73,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;fd6lq&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;96it0&quot;,&quot;text&quot;:&quot;EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado en alinear h\u00e1bitos de comportamiento y crear nuevos para mantener un estilo de vida saludable el resto de tu vida. &quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:57,&quot;style&quot;:&quot;BOLD&quot;},{&quot;offset&quot;:74,&quot;length&quot;:28,&quot;style&quot;:&quot;BOLD&quot;},{&quot;offset&quot;:103,&quot;length&quot;:56,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;akeoo&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;3og4h&quot;,&quot;text&quot;:&quot;El concepto de EFT es en realidad una incubadora de desarrollo y superaci\u00f3n personal disfrazada de programa deportivo. Su misi\u00f3n es llegar a transformar por lo menos 1 mill\u00f3n de vidas. &quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:119,&quot;style&quot;:&quot;BOLD&quot;},{&quot;offset&quot;:122,&quot;length&quot;:7,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;8a2ib&quot;,&quot;text&quot;:&quot; &quot;,&quot;type&quot;:&quot;atomic&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:1,&quot;key&quot;:1}],&quot;data&quot;:{}},{&quot;key&quot;:&quot;701ua&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;f4sfv&quot;,&quot;text&quot;:&quot;EFT es un m\u00e9todo de entrenamientos conformado por un h\u00edbrido de diferentes disciplinas funcionales. Es una mezcla entre bootcamp, insanity, TRX, pretemporada de soccer, pretemporada de de americano y piezas de musculaci\u00f3n.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:4,&quot;length&quot;:96,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;5qa7g&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;fgao3&quot;,&quot;text&quot;:&quot;Los entrenamientos cuentan con la siguiente mec\u00e1nica de tiempo, tienen una duraci\u00f3n de 60 minutos, 5 d\u00edas por semana, por 42 d\u00edas intensivos. Nunca se repite una sola sesi\u00f3n de entrenamiento, siempre es distinto y hay una planeaci\u00f3n con el objetivo de que trabajes todo tu cuerpo y siempre sea din\u00e1mico.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:87,&quot;length&quot;:54,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;cbokp&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;b3epo&quot;,&quot;text&quot;:&quot;Dentro de los principales beneficios f\u00edsicos est\u00e1 el bajar el % de grasa y aumento de masa muscular que te hace ver m\u00e1s est\u00e9tico. En cuanto a beneficios deportivos se logra incrementar la fuerza, resistencia, potencia, flexibilidad, coordinaci\u00f3n, entre otras habilidades que se van desarrollando en cada persona.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:26,&quot;length&quot;:19,&quot;style&quot;:&quot;BOLD&quot;},{&quot;offset&quot;:142,&quot;length&quot;:21,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;c6vcv&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;ecc69&quot;,&quot;text&quot;:&quot;En el tema an\u00edmico se enfocan en el desarrollo humano, emocional, ayud\u00e1ndote a lograr el triple de energ\u00eda, 80% menos estr\u00e9s y 80% ansiedad.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:6,&quot;length&quot;:12,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;b3lh8&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;2seci&quot;,&quot;text&quot;:&quot;La suma de estas 3 partes espec\u00edficamente te permite aumentar el nivel de autoestima, seguridad y confianza, ver y percibir el mundo diferente, logrando objetivos y haciendo las cosas de manera distinta.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:26,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;8eela&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;alrb2&quot;,&quot;text&quot;:&quot;Todos los instructores son atletas de alto rendimiento, jugadores pro de futbol americano, bailarinas profesionales, competidores de crossfit profesionales, etc\u2026 y cada uno cuenta con sus respectivas certificaciones y especialidades.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:55,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;fcjoo&quot;,&quot;text&quot;:&quot; &quot;,&quot;type&quot;:&quot;atomic&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:1,&quot;key&quot;:2}],&quot;data&quot;:{}},{&quot;key&quot;:&quot;g29c&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;f36gn&quot;,&quot;text&quot;:&quot;Es un ambiente 100% familiar y a la vez de gran compromiso y dedicaci\u00f3n, una comunidad que se vuelve familia, un ambiente de mucho empoderamiento y superaci\u00f3n personal. &quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:6,&quot;length&quot;:66,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;363bb&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;9qj5q&quot;,&quot;text&quot;:&quot;Organizan los EFT games, que son competencias sanas y se arman en formato de juegos donde hay 1 ganador con el objetivo de motivar a los usuarios. Adem\u00e1s hacen salidas los fines de semana a la barranca, hacer carreras, etc...&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:14,&quot;length&quot;:11,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;165jg&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;7ps7q&quot;,&quot;text&quot;:&quot;Te recomendamos llegar 5 minutos antes de la sesi\u00f3n de entrenamiento, traer toalla para el sudor y haber consumido un snack de m\u00ednimo 1 hora a 40 mins antes del entrenamiento. &quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:15,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;5a5is&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;9frbp&quot;,&quot;text&quot;:&quot;\u00bfQu\u00e9 esperas para conocerlos? Reserva tus clases por medio de la App de Fitpass M\u00e9xico y s\u00edguenos en Facebook: Fitpass M\u00e9xico o Instagram: @Fitpassmx para estar al tanto de nuestros tips y promociones.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:201,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;776i0&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;db12s&quot;,&quot;text&quot;:&quot;Emotional Fitness Training | Lapizl\u00e1zuli #3458, Col. Residencial Victoria, Zapopan, Jalisco | Facebook: Emotional Fitness Training | Instagram: @emotionalfitnesstraining&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:169,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;e3ge6&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;479bs&quot;,&quot;text&quot;:&quot;&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;6oq8v&quot;,&quot;text&quot;:&quot;Por: Pau Barrera&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:16,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;2pl7i&quot;,&quot;text&quot;:&quot;_________________&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[],&quot;entityRanges&quot;:[],&quot;data&quot;:{}},{&quot;key&quot;:&quot;8ufn7&quot;,&quot;text&quot;:&quot;Paulina Barrera Arrieta, es egresada de Comunicaci\u00f3n y Publicidad de la Universidad Panamericana de la ciudad de Guadalajara. Ha trabajado en diferentes empresas de Publicidad, Marketing &amp; Medios Digitales y cuenta con m\u00e1s de 5 a\u00f1os de experiencia en el medio. Amante del tenis y el box.&quot;,&quot;type&quot;:&quot;unstyled&quot;,&quot;depth&quot;:0,&quot;inlineStyleRanges&quot;:[{&quot;offset&quot;:0,&quot;length&quot;:24,&quot;style&quot;:&quot;BOLD&quot;}],&quot;entityRanges&quot;:[],&quot;data&quot;:{}}],&quot;entityMap&quot;:{&quot;0&quot;:{&quot;type&quot;:&quot;wix-draft-plugin-image&quot;,&quot;mutability&quot;:&quot;IMMUTABLE&quot;,&quot;data&quot;:{&quot;config&quot;:{&quot;alignment&quot;:&quot;center&quot;,&quot;size&quot;:&quot;content&quot;,&quot;showTitle&quot;:true,&quot;showDescription&quot;:true,&quot;link&quot;:{&quot;url&quot;:&quot;https:\/\/www.instagram.com\/emotionalfitnesstraining\/?hl=en&quot;,&quot;target&quot;:&quot;_blank&quot;,&quot;rel&quot;:&quot;noopener&quot;},&quot;textWrap&quot;:&quot;wrap&quot;},&quot;src&quot;:{&quot;id&quot;:&quot;1835d0_574920755d3147cdb6b0ec82872e68a4~mv2.jpg&quot;,&quot;original_file_name&quot;:&quot;1835d0_574920755d3147cdb6b0ec82872e68a4~mv2.jpg&quot;,&quot;file_name&quot;:&quot;1835d0_574920755d3147cdb6b0ec82872e68a4~mv2.jpg&quot;,&quot;width&quot;:485,&quot;height&quot;:443}}},&quot;1&quot;:{&quot;type&quot;:&quot;wix-draft-plugin-image&quot;,&quot;mutability&quot;:&quot;IMMUTABLE&quot;,&quot;data&quot;:{&quot;config&quot;:{&quot;alignment&quot;:&quot;center&quot;,&quot;size&quot;:&quot;content&quot;,&quot;showTitle&quot;:true,&quot;showDescription&quot;:true,&quot;link&quot;:{&quot;url&quot;:&quot;https:\/\/www.instagram.com\/p\/By3B6fnHkLZ\/&quot;,&quot;target&quot;:&quot;_blank&quot;,&quot;rel&quot;:&quot;noopener&quot;},&quot;textWrap&quot;:&quot;wrap&quot;},&quot;src&quot;:{&quot;id&quot;:&quot;1835d0_1720eabd7c764d47b3ec5d8e8879623f~mv2.png&quot;,&quot;original_file_name&quot;:&quot;1835d0_1720eabd7c764d47b3ec5d8e8879623f~mv2.png&quot;,&quot;file_name&quot;:&quot;1835d0_1720eabd7c764d47b3ec5d8e8879623f~mv2.png&quot;,&quot;width&quot;:909,&quot;height&quot;:425}}},&quot;2&quot;:{&quot;type&quot;:&quot;wix-draft-plugin-image&quot;,&quot;mutability&quot;:&quot;IMMUTABLE&quot;,&quot;data&quot;:{&quot;config&quot;:{&quot;alignment&quot;:&quot;center&quot;,&quot;size&quot;:&quot;content&quot;,&quot;showTitle&quot;:true,&quot;showDescription&quot;:true,&quot;link&quot;:{&quot;url&quot;:&quot;https:\/\/www.instagram.com\/p\/BxfbnrSl_Pr\/&quot;,&quot;target&quot;:&quot;_blank&quot;,&quot;rel&quot;:&quot;noopener&quot;},&quot;textWrap&quot;:&quot;wrap&quot;},&quot;src&quot;:{&quot;id&quot;:&quot;1835d0_b7ae2622d08b40919455b2840ce5328c~mv2.png&quot;,&quot;original_file_name&quot;:&quot;1835d0_b7ae2622d08b40919455b2840ce5328c~mv2.png&quot;,&quot;file_name&quot;:&quot;1835d0_b7ae2622d08b40919455b2840ce5328c~mv2.png&quot;,&quot;width&quot;:920,&quot;height&quot;:584}}}},&quot;VERSION&quot;:&quot;9.3.6&quot;}\">\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"foo-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"foo-0-0\"><span data-offset-key=\"foo-0-0\">Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"2hqlt-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2hqlt-0-0\"><span data-offset-key=\"2hqlt-0-0\">Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte<\/span><span data-offset-key=\"2hqlt-0-1\"> es que nace la idea de Emotional Fitness Training en enero del 2017.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"4u0j7-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"4u0j7-0-0\"><span data-offset-key=\"4u0j7-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"d5ga9-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"d5ga9-0-0\"><span data-offset-key=\"d5ga9-0-0\">EFT o mejor conocido como Emotional Fitness es un studio <\/span><span data-offset-key=\"d5ga9-0-1\">cuyos fundadores <\/span><span data-offset-key=\"d5ga9-0-2\">desarrollan el programa E42,<\/span> <span data-offset-key=\"d5ga9-0-4\">un programa de entrenamiento f\u00edsico, mental y emocional <\/span><span data-offset-key=\"d5ga9-0-5\">enfocado en alinear h\u00e1bitos de comportamiento y crear nuevos para mantener un estilo de vida saludable el resto de tu vida. <\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"c5l94-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"c5l94-0-0\"><span data-offset-key=\"c5l94-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"3hbq9-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"3hbq9-0-0\"><span data-offset-key=\"3hbq9-0-0\">El concepto de EFT es en realidad una incubadora de desarrollo y superaci\u00f3n personal disfrazada de programa deportivo. <\/span><span data-offset-key=\"3hbq9-0-1\">Su <\/span><span data-offset-key=\"3hbq9-0-2\">misi\u00f3n <\/span><span data-offset-key=\"3hbq9-0-3\">es llegar a transformar por lo menos 1 mill\u00f3n de vidas. <\/span><\/div>\n<div data-offset-key=\"3hbq9-0-0\"><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"c0jp4-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"c0jp4-0-0\"><span data-offset-key=\"c0jp4-0-0\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4006\" src=\"http:\/\/amak.mx\/fitpass\/wp-content\/uploads\/2022\/12\/1835d0_1720eabd7c764d47b3ec5d8e8879623fmv2.webp\" alt=\"\" width=\"909\" height=\"425\" \/><\/span><\/div>\n<div data-offset-key=\"c0jp4-0-0\"><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"9if2r-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"9if2r-0-0\"><span data-offset-key=\"9if2r-0-0\">EFT <\/span><span data-offset-key=\"9if2r-0-1\">es un m\u00e9todo de entrenamientos conformado por un h\u00edbrido de diferentes disciplinas funcionales. <\/span><span data-offset-key=\"9if2r-0-2\">Es una mezcla entre bootcamp, insanity, TRX, pretemporada de soccer, pretemporada de de americano y piezas de musculaci\u00f3n.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"1vgn9-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1vgn9-0-0\"><span data-offset-key=\"1vgn9-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"9u13p-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"9u13p-0-0\"><span data-offset-key=\"9u13p-0-0\">Los entrenamientos cuentan con la siguiente mec\u00e1nica de tiempo, tienen una duraci\u00f3n de <\/span><span data-offset-key=\"9u13p-0-1\">60 minutos, 5 d\u00edas por semana, por 42 d\u00edas intensivos.<\/span><span data-offset-key=\"9u13p-0-2\"> Nunca se repite una sola sesi\u00f3n de entrenamiento, siempre es distinto y hay una planeaci\u00f3n con el objetivo de que trabajes todo tu cuerpo y siempre sea din\u00e1mico.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"fosi2-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"fosi2-0-0\"><span data-offset-key=\"fosi2-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"5lmqv-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"5lmqv-0-0\"><span data-offset-key=\"5lmqv-0-0\">Dentro de los principales <\/span><span data-offset-key=\"5lmqv-0-1\">beneficios f\u00edsicos <\/span><span data-offset-key=\"5lmqv-0-2\">est\u00e1 el bajar el % de grasa y aumento de masa muscular que te hace ver m\u00e1s est\u00e9tico. En cuanto a <\/span><span data-offset-key=\"5lmqv-0-3\">beneficios deportivos<\/span><span data-offset-key=\"5lmqv-0-4\"> se logra incrementar la fuerza, resistencia, potencia, flexibilidad, coordinaci\u00f3n, entre otras habilidades que se van desarrollando en cada persona.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"13a8p-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"13a8p-0-0\"><span data-offset-key=\"13a8p-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"bblh2-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"bblh2-0-0\"><span data-offset-key=\"bblh2-0-0\">En el <\/span><span data-offset-key=\"bblh2-0-1\">tema an\u00edmico<\/span><span data-offset-key=\"bblh2-0-2\"> se enfocan en el desarrollo humano, emocional, ayud\u00e1ndote a lograr el triple de energ\u00eda, 80% menos estr\u00e9s y 80% ansiedad.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"eg4ah-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"eg4ah-0-0\"><span data-offset-key=\"eg4ah-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"3r9jd-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"3r9jd-0-0\"><span data-offset-key=\"3r9jd-0-0\">La suma de estas 3 partes <\/span><span data-offset-key=\"3r9jd-0-1\">espec\u00edficamente te permite aumentar el nivel de autoestima, seguridad y confianza, ver y percibir el mundo diferente, logrando objetivos y haciendo las cosas de manera distinta.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"dr6vu-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"dr6vu-0-0\"><span data-offset-key=\"dr6vu-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"12qer-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"12qer-0-0\"><span data-offset-key=\"12qer-0-0\">Todos los instructores son atletas de alto rendimiento,<\/span><span data-offset-key=\"12qer-0-1\"> jugadores pro de futbol americano, bailarinas profesionales, competidores de crossfit profesionales, etc\u2026 y cada uno cuenta con sus respectivas certificaciones y especialidades.<\/span><\/div>\n<div data-offset-key=\"12qer-0-0\"><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"akta3-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"akta3-0-0\"><span data-offset-key=\"akta3-0-0\"><img decoding=\"async\" class=\"alignnone size-full wp-image-4008\" src=\"http:\/\/amak.mx\/fitpass\/wp-content\/uploads\/2022\/12\/1835d0_b7ae2622d08b40919455b2840ce5328cmv2.webp\" alt=\"\" width=\"919\" height=\"584\" \/><\/span><\/div>\n<div data-offset-key=\"akta3-0-0\"><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"824rl-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"824rl-0-0\"><span data-offset-key=\"824rl-0-0\">Es un <\/span><span data-offset-key=\"824rl-0-1\">ambiente 100% familiar y a la vez de gran compromiso y dedicaci\u00f3n,<\/span><span data-offset-key=\"824rl-0-2\"> una comunidad que se vuelve familia, un ambiente de mucho empoderamiento y superaci\u00f3n personal. <\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"51g6s-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"51g6s-0-0\"><span data-offset-key=\"51g6s-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"40n7-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"40n7-0-0\"><span data-offset-key=\"40n7-0-0\">Organizan los <\/span><span data-offset-key=\"40n7-0-1\">EFT games, <\/span><span data-offset-key=\"40n7-0-2\">que son competencias sanas y se arman en formato de juegos donde hay 1 ganador con el objetivo de motivar a los usuarios. Adem\u00e1s hacen salidas los fines de semana a la barranca, hacer carreras, etc&#8230;<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"ah7h0-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"ah7h0-0-0\"><span data-offset-key=\"ah7h0-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"2ido5-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"2ido5-0-0\"><span data-offset-key=\"2ido5-0-0\">Te recomendamos<\/span><span data-offset-key=\"2ido5-0-1\"> llegar 5 minutos antes de la sesi\u00f3n de entrenamiento, traer toalla para el sudor y haber consumido un snack de m\u00ednimo 1 hora a 40 mins antes del entrenamiento. <\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"1lrrh-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"1lrrh-0-0\"><span data-offset-key=\"1lrrh-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"35b7o-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"35b7o-0-0\"><span data-offset-key=\"35b7o-0-0\">\u00bfQu\u00e9 esperas para conocerlos? Reserva tus clases por medio de la App de Fitpass M\u00e9xico y s\u00edguenos en Facebook: Fitpass M\u00e9xico o Instagram: @Fitpassmx para estar al tanto de nuestros tips y promociones.<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"asr9s-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"asr9s-0-0\"><span data-offset-key=\"asr9s-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"bc1tr-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"bc1tr-0-0\"><span data-offset-key=\"bc1tr-0-0\">Emotional Fitness Training | Lapizl\u00e1zuli #3458, Col. Residencial Victoria, Zapopan, Jalisco | Facebook: Emotional Fitness Training | Instagram: @emotionalfitnesstraining<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"e7v9e-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"e7v9e-0-0\"><span data-offset-key=\"e7v9e-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"esbjn-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"esbjn-0-0\"><span data-offset-key=\"esbjn-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"emjfm-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"emjfm-0-0\"><span data-offset-key=\"emjfm-0-0\">Por: Pau Barrera<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"857n7-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"857n7-0-0\"><span data-offset-key=\"857n7-0-0\">_________________<\/span><\/div>\n<\/div>\n<div class=\"_25Ehb _3qYRK Oh89J public-DraftStyleDefault-block-depth0 public-DraftStyleDefault-text-ltr fixed-tab-size rich_content_P\" data-block=\"true\" data-editor=\"editor\" data-offset-key=\"5i330-0-0\">\n<div class=\"public-DraftStyleDefault-block public-DraftStyleDefault-ltr\" data-offset-key=\"5i330-0-0\"><span data-offset-key=\"5i330-0-0\">Paulina Barrera Arrieta,<\/span><span data-offset-key=\"5i330-0-1\"> es egresada de Comunicaci\u00f3n y Publicidad de la Universidad Panamericana de la ciudad de Guadalajara. Ha trabajado en diferentes empresas de Publicidad, Marketing &amp; Medios Digitales y cuenta con m\u00e1s de 5 a\u00f1os de experiencia en el medio. Amante del tenis y el box.<\/span><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emotional Fitness Training GDL - Blog Fitpass<\/title>\n<meta name=\"description\" content=\"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emotional Fitness Training GDL - Blog Fitpass\" \/>\n<meta property=\"og:description\" content=\"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Fitpass\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-27T02:48:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T19:16:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fitpass.com\/mx\/blog\/wp-content\/uploads\/2022\/12\/1835d0_574920755d3147cdb6b0ec82872e68a4mv2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"582\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Fitpass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fitpass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/\",\"url\":\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/\",\"name\":\"Emotional Fitness Training GDL - Blog Fitpass\",\"isPartOf\":{\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/#website\"},\"datePublished\":\"2019-09-27T02:48:25+00:00\",\"dateModified\":\"2025-07-09T19:16:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/b01908891743dbd2fc930eb863890c3c\"},\"description\":\"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.fitpass.com\/mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emotional Fitness Training GDL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/#website\",\"url\":\"https:\/\/www.fitpass.com\/mx\/blog\/\",\"name\":\"Blog Fitpass\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fitpass.com\/mx\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/b01908891743dbd2fc930eb863890c3c\",\"name\":\"Fitpass\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d6e7c090ed2ddfcf32d02d53a1c812b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d6e7c090ed2ddfcf32d02d53a1c812b3?s=96&d=mm&r=g\",\"caption\":\"Fitpass\"},\"url\":\"https:\/\/www.fitpass.com\/mx\/blog\/author\/fitpass\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emotional Fitness Training GDL - Blog Fitpass","description":"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/","og_locale":"es_MX","og_type":"article","og_title":"Emotional Fitness Training GDL - Blog Fitpass","og_description":"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado","og_url":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/","og_site_name":"Blog Fitpass","article_published_time":"2019-09-27T02:48:25+00:00","article_modified_time":"2025-07-09T19:16:07+00:00","og_image":[{"width":582,"height":532,"url":"https:\/\/www.fitpass.com\/mx\/blog\/wp-content\/uploads\/2022\/12\/1835d0_574920755d3147cdb6b0ec82872e68a4mv2.webp","type":"image\/webp"}],"author":"Fitpass","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Fitpass","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/","url":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/","name":"Emotional Fitness Training GDL - Blog Fitpass","isPartOf":{"@id":"https:\/\/www.fitpass.com\/mx\/blog\/#website"},"datePublished":"2019-09-27T02:48:25+00:00","dateModified":"2025-07-09T19:16:07+00:00","author":{"@id":"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/b01908891743dbd2fc930eb863890c3c"},"description":"Un studio basado en la f\u00f3rmula EFT que es un sistema de empoderamiento f\u00edsico, mental y emocional. Los Programas EFT fueron dise\u00f1ados para transformar el cuerpo y h\u00e1bitos en tiempo r\u00e9cord. Con el objetivo de empoderar la vida de las personas a trav\u00e9s del deporte es que nace la idea de Emotional Fitness Training en enero del 2017. EFT o mejor conocido como Emotional Fitness es un studio cuyos fundadores desarrollan el programa E42, un programa de entrenamiento f\u00edsico, mental y emocional enfocado","breadcrumb":{"@id":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fitpass.com\/mx\/blog\/2019\/09\/27\/emotional-fitness-training-gdl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.fitpass.com\/mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Emotional Fitness Training GDL"}]},{"@type":"WebSite","@id":"https:\/\/www.fitpass.com\/mx\/blog\/#website","url":"https:\/\/www.fitpass.com\/mx\/blog\/","name":"Blog Fitpass","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fitpass.com\/mx\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Person","@id":"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/b01908891743dbd2fc930eb863890c3c","name":"Fitpass","image":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.fitpass.com\/mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d6e7c090ed2ddfcf32d02d53a1c812b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6e7c090ed2ddfcf32d02d53a1c812b3?s=96&d=mm&r=g","caption":"Fitpass"},"url":"https:\/\/www.fitpass.com\/mx\/blog\/author\/fitpass\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/4005"}],"collection":[{"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/comments?post=4005"}],"version-history":[{"count":1,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/4005\/revisions"}],"predecessor-version":[{"id":4009,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/posts\/4005\/revisions\/4009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/media\/4007"}],"wp:attachment":[{"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/media?parent=4005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/categories?post=4005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fitpass.com\/mx\/blog\/wp-json\/wp\/v2\/tags?post=4005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}